{"id":15508,"date":"2014-07-23T11:49:50","date_gmt":"2014-07-23T11:49:50","guid":{"rendered":"http:\/\/demo.qodeinteractive.com\/bridge24\/?page_id=15508"},"modified":"2024-01-03T14:49:39","modified_gmt":"2024-01-03T14:49:39","slug":"home-7","status":"publish","type":"page","link":"https:\/\/pujolims.com\/","title":{"rendered":"HOME PUJOL"},"content":{"rendered":"<p>[vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbgrid\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbcenter\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb padding_top=\u00bb65&#8243; padding_bottom=\u00bb118&#8243; anchor=\u00bbabout\u00bb][vc_column][vc_column_text]<\/p>\n<h2 style=\"text-align: center;\">Sobre nosaltres<\/h2>\n<p>[\/vc_column_text][vc_separator type=\u00bbsmall\u00bb position=\u00bbcenter\u00bb color=\u00bb#001d7e\u00bb][vc_column_text]<\/p>\n<p style=\"text-align: center;\"><strong>Pujol ims \u00e9s una empresa formada per un equip jove i din\u00e0mic ben qualificat, per al que l\u2019objectiu m\u00e9s important \u00e9s la satisfacci\u00f3 dels nostres clients junt amb un servei eficient i de qualitat sempre amb el rigor\u00f3s compliment de les normatives de seguretat i legalitat tant de les persones com dels equipaments.<\/strong><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbgrid\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb padding_bottom=\u00bb94&#8243;][vc_column width=\u00bb1\/3&#8243;]<div class='q_icon_with_title medium custom_icon_image center '><div class=\"icon_holder \" style=\"margin: 0 0 40px 0; \"><img itemprop=\"image\" style=\"margin: 0 0 40px 0;\" src=\"https:\/\/pujolims.com\/wp-content\/uploads\/2020\/08\/instalacions.png\" alt=\"\"><\/div><div class=\"icon_text_holder\" style=\"\"><div class=\"icon_text_inner\" style=\"\"><h5 class=\"icon_title\" style=\"\">INSTAL\u00b7LACIONS<\/h5><p style=''>Fem instal\u00b7lacions industrials i dom\u00e8stiques<\/p><\/div><\/div><\/div>[\/vc_column][vc_column width=\u00bb1\/3&#8243;]<div class='q_icon_with_title medium custom_icon_image center '><div class=\"icon_holder \" style=\"margin: 0 0 40px 0; \"><img itemprop=\"image\" style=\"margin: 0 0 40px 0;\" src=\"https:\/\/pujolims.com\/wp-content\/uploads\/2020\/08\/manteniment-pujol-ims.png\" alt=\"\"><\/div><div class=\"icon_text_holder\" style=\"\"><div class=\"icon_text_inner\" style=\"\"><h5 class=\"icon_title\" style=\"\">MANTENIMENT<\/h5><p style=''>Manteniment de tot tipus d'instal\u00b7lacions el\u00e8ctriques<\/p><\/div><\/div><\/div>[\/vc_column][vc_column width=\u00bb1\/3&#8243;]<div class='q_icon_with_title medium custom_icon_image center '><div class=\"icon_holder \" style=\"margin: 0 0 40px 0; \"><img itemprop=\"image\" style=\"margin: 0 0 40px 0;\" src=\"https:\/\/pujolims.com\/wp-content\/uploads\/2020\/08\/serveis-pujol-ims.png\" alt=\"\"><\/div><div class=\"icon_text_holder\" style=\"\"><div class=\"icon_text_inner\" style=\"\"><h5 class=\"icon_title\" style=\"\">SERVEIS<\/h5><p style=''>Donem serveis el\u00e8ctric tant industrial com dom\u00e8stic<\/p><\/div><\/div><\/div>[\/vc_column][\/vc_row][vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbgrid\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwith_pattern\u00bb background_color=\u00bb#353535&#8243; background_image=\u00bb15540&#8243; padding_top=\u00bb114&#8243; padding_bottom=\u00bb122&#8243;][vc_column width=\u00bb1\/2&#8243;][vc_column_text]<\/p>\n<h5><span style=\"color: #ffffff;\">CAMPS DE TREBALL<\/span><\/h5>\n<p>[\/vc_column_text][vc_separator type=\u00bbtransparent\u00bb up=\u00bb33&#8243;][vc_column_text]<span style=\"color: #ffffff;\"><strong>ELECTRICITAT<\/strong><\/span><\/p>\n<ul>\n<li><span style=\"color: #ffffff;\">Disseny, construcci\u00f3 i manteniment d\u2019instal.lacions de baixa tensi\u00f3 tant industrials com dom\u00e8stiques.<\/span><\/li>\n<li><span style=\"color: #ffffff;\">Manteniment el\u00e8ctric de pivots i sistemes de reg.<\/span><\/li>\n<li><span style=\"color: #ffffff;\">Disseny i muntatge de quadres generals de distribuci\u00f3.<\/span><\/li>\n<li><span style=\"color: #ffffff;\">Automatitzacions d\u2019instal.lacions existents amb tecnologies de telegesti\u00f3.<\/span><\/li>\n<li><span style=\"color: #ffffff;\">Muntatge i manteniment de xarxes d\u2019enllumenat p\u00fablic.<\/span><\/li>\n<li><span style=\"color: #ffffff;\">Instal\u00b7laci\u00f3 de punts de rec\u00e0rrega r\u00e1pida de vehicles el\u00e8ctrics.<\/span><\/li>\n<li><span style=\"color: #ffffff;\">Creaci\u00f3 d\u2019ambients acollidors amb tot un ventall d\u2019elements d\u2019il.luminaci\u00f3.<\/span><\/li>\n<li><span style=\"color: #ffffff;\">Manteniment integral de comunitats de propietaris.<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ffffff;\"><strong>ENERG\u00cdA SOLAR<\/strong><\/span><\/p>\n<ul>\n<li><span style=\"color: #ffffff;\">Disseny i muntatge d\u2019instal.lacions solars tant d\u2019autoconsum com de petits subministraments.<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ffffff;\"><strong>\u00a0<\/strong><\/span><\/p>\n<p><span style=\"color: #ffffff;\"><strong>TELECOMUNICACIONS<\/strong><\/span>[\/vc_column_text][\/vc_column][vc_column width=\u00bb1\/2&#8243;][vc_column_text]<\/p>\n<p>[\/vc_column_text][vc_separator type=\u00bbtransparent\u00bb up=\u00bb33&#8243;][vc_column_text]<span style=\"color: #ffffff;\"><strong>DADES<\/strong><\/span><\/p>\n<ul>\n<li><span style=\"color: #ffffff;\">Disseny, muntatge, posada en funcionament i manteniment de xarxes integrals d\u2019inform\u00e0tica amb les m\u00e9s avan\u00e7ades tecnologies.<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ffffff;\"><strong>\u00a0<\/strong><\/span><\/p>\n<p><span style=\"color: #ffffff;\"><strong>IMATGE, VEU I S\u00d2<\/strong><\/span><\/p>\n<ul>\n<li><span style=\"color: #ffffff;\">Instal\u00b7lacions i manteniment integral de xarxes de TV i satel.lit.<\/span><\/li>\n<li><span style=\"color: #ffffff;\">Instal\u00b7laci\u00f3 i manteniment de porters i videoporters.<\/span><\/li>\n<li><span style=\"color: #ffffff;\">Disseny i muntatge de xarxes de megafon\u00eda i fil musical.<\/span><\/li>\n<\/ul>\n<p><span style=\"color: #ffffff;\"><strong>SEGURETAT<\/strong><\/span><\/p>\n<ul>\n<li><span style=\"color: #ffffff;\">Disseny, instal.laci\u00f3 i manteniment de sistemes contraincendis, alarmes i videovigilancies.<\/span><\/li>\n<li><span style=\"color: #ffffff;\">Instal\u00b7laci\u00f3 de sistemes antip\u00e0nic per a persones vulnerables.<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ffffff;\"><strong>\u00a0<\/strong><\/span><\/p>\n<p><span style=\"color: #ffffff;\"><strong>Climatitzaci\u00f3<\/strong><\/span><\/p>\n<ul>\n<li><span style=\"color: #ffffff;\">Instal\u00b7laci\u00f3 i manteniment d\u2019equips de climatitzaci\u00f3 industrial i dom\u00e8stica.<\/span><\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbgrid\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb padding_top=\u00bb111&#8243; padding_bottom=\u00bb34&#8243; anchor=\u00bbservices\u00bb][vc_column width=\u00bb1\/4&#8243;]<div class='q_icon_with_title very_large custom_icon_image left_from_title '><div class=\"icon_text_holder\" style=\"padding-left:88px;\"><div class=\"icon_text_inner\" style=\"\"><div class=\"icon_title_holder\"><div class=\"icon_holder \" style=\" \"><img itemprop=\"image\" style=\"\" src=\"https:\/\/pujolims.com\/wp-content\/uploads\/2021\/05\/iconos-treballs-pujolims-01.png\" alt=\"\"><\/div><h5 class=\"icon_title\" style=\"\">Plaques solars<\/h5><\/div><p style=''><\/p><\/div><\/div><\/div>[vc_separator type=\u00bbtransparent\u00bb up=\u00bb20&#8243;][\/vc_column][vc_column width=\u00bb1\/4&#8243;]<div class='q_icon_with_title very_large custom_icon_image left_from_title '><div class=\"icon_text_holder\" style=\"padding-left:88px;\"><div class=\"icon_text_inner\" style=\"\"><div class=\"icon_title_holder\"><div class=\"icon_holder \" style=\" \"><img itemprop=\"image\" style=\"\" src=\"https:\/\/pujolims.com\/wp-content\/uploads\/2021\/05\/iconos-treballs-pujolims-02.png\" alt=\"\"><\/div><h5 class=\"icon_title\" style=\"\">Antenes TV<\/h5><\/div><p style=''><\/p><\/div><\/div><\/div>[vc_separator type=\u00bbtransparent\u00bb up=\u00bb20&#8243;][\/vc_column][vc_column width=\u00bb1\/4&#8243;]<div class='q_icon_with_title very_large custom_icon_image left_from_title '><div class=\"icon_text_holder\" style=\"padding-left:88px;\"><div class=\"icon_text_inner\" style=\"\"><div class=\"icon_title_holder\"><div class=\"icon_holder \" style=\" \"><img itemprop=\"image\" style=\"\" src=\"https:\/\/pujolims.com\/wp-content\/uploads\/2021\/05\/iconos-treballs-pujolims-03.png\" alt=\"\"><\/div><h5 class=\"icon_title\" style=\"\">Porters autom\u00e0tics<\/h5><\/div><p style=''><\/p><\/div><\/div><\/div>[vc_separator type=\u00bbtransparent\u00bb up=\u00bb20&#8243;][\/vc_column][vc_column width=\u00bb1\/4&#8243;]<div class='q_icon_with_title very_large custom_icon_image left_from_title '><div class=\"icon_text_holder\" style=\"padding-left:88px;\"><div class=\"icon_text_inner\" style=\"\"><div class=\"icon_title_holder\"><div class=\"icon_holder \" style=\" \"><img itemprop=\"image\" style=\"\" src=\"https:\/\/pujolims.com\/wp-content\/uploads\/2021\/05\/iconos-treballs-pujolims-05.png\" alt=\"\"><\/div><h5 class=\"icon_title\" style=\"\">Xarxa inform\u00e0tica<\/h5><\/div><p style=''><\/p><\/div><\/div><\/div>[\/vc_column][\/vc_row][vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbgrid\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb padding_bottom=\u00bb84&#8243;][vc_column width=\u00bb1\/3&#8243;]<div class='q_icon_with_title very_large custom_icon_image left_from_title '><div class=\"icon_text_holder\" style=\"padding-left:88px;\"><div class=\"icon_text_inner\" style=\"\"><div class=\"icon_title_holder\"><div class=\"icon_holder \" style=\" \"><img itemprop=\"image\" style=\"\" src=\"https:\/\/pujolims.com\/wp-content\/uploads\/2021\/05\/iconos-treballs-pujolims-07.png\" alt=\"\"><\/div><h5 class=\"icon_title\" style=\"\">Quadres el\u00e8ctrics<\/h5><\/div><p style=''><\/p><\/div><\/div><\/div>[vc_separator type=\u00bbtransparent\u00bb up=\u00bb20&#8243;][\/vc_column][vc_column width=\u00bb1\/3&#8243;]<div class='q_icon_with_title very_large custom_icon_image left_from_title '><div class=\"icon_text_holder\" style=\"padding-left:88px;\"><div class=\"icon_text_inner\" style=\"\"><div class=\"icon_title_holder\"><div class=\"icon_holder \" style=\" \"><img itemprop=\"image\" style=\"\" src=\"https:\/\/pujolims.com\/wp-content\/uploads\/2021\/05\/iconos-treballs-pujolims-06.png\" alt=\"\"><\/div><h5 class=\"icon_title\" style=\"\">Pivots<\/h5><\/div><p style=''><\/p><\/div><\/div><\/div>[vc_separator type=\u00bbtransparent\u00bb up=\u00bb20&#8243;][\/vc_column][vc_column width=\u00bb1\/3&#8243;]<div class='q_icon_with_title very_large custom_icon_image left_from_title '><div class=\"icon_text_holder\" style=\"\"><div class=\"icon_text_inner\" style=\"\"><div class=\"icon_title_holder\"><div class=\"icon_holder \" style=\" \"><img itemprop=\"image\" style=\"\" src=\"https:\/\/pujolims.com\/wp-content\/uploads\/2021\/05\/iconos-treballs-pujolims-04.png\" alt=\"\"><\/div><h5 class=\"icon_title\" style=\"\">Gesti\u00f3 a dist\u00e0ncia<\/h5><\/div><p style=''><\/p><\/div><\/div><\/div>[vc_separator type=\u00bbtransparent\u00bb up=\u00bb20&#8243;][\/vc_column][\/vc_row][vc_row row_type=\u00bbparallax\u00bb parallax_content_width=\u00bbin_grid\u00bb text_align=\u00bbcenter\u00bb full_screen_section_height=\u00bbno\u00bb background_image=\u00bb15910&#8243; section_height=\u00bb374&#8243;][vc_column][vc_separator type=\u00bbtransparent\u00bb thickness=\u00bb1&#8243; up=\u00bb89&#8243; down=\u00bb0&#8243;][vc_row_inner row_type=\u00bbrow\u00bb type=\u00bbgrid\u00bb text_align=\u00bbleft\u00bb css_animation=\u00bb\u00bb][vc_column_inner width=\u00bb1\/3&#8243;]<div class=\"q_counter_holder  center\" style=\"\" data-digit=\"134\"><span class=\"counter  zero\" style=\"\">134<\/span><p class=\"counter_text\" style=\"\">Instal\u00b7lacions comercials<\/p><\/div>[vc_separator type=\u00bbtransparent\u00bb up=\u00bb20&#8243;][\/vc_column_inner][vc_column_inner width=\u00bb1\/3&#8243;]<div class=\"q_counter_holder  center\" style=\"\" data-digit=\"500\"><span class=\"counter  zero\" style=\"\">500<\/span><p class=\"counter_text\" style=\"\">Instal\u00b7lacions dom\u00e8stiques<\/p><\/div>[vc_separator type=\u00bbtransparent\u00bb up=\u00bb20&#8243;][\/vc_column_inner][vc_column_inner width=\u00bb1\/3&#8243;]<div class=\"q_counter_holder  center\" style=\"\" data-digit=\"634\"><span class=\"counter  zero\" style=\"\">634<\/span><p class=\"counter_text\" style=\"\">Clients contents<\/p><\/div>[vc_separator type=\u00bbtransparent\u00bb up=\u00bb20&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbgrid\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbcenter\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb padding_top=\u00bb79&#8243; padding_bottom=\u00bb43&#8243; anchor=\u00bbportfolio\u00bb][vc_column][vc_column_text]<\/p>\n<h2 style=\"text-align: center;\">Els nostres treballs<\/h2>\n<p>[\/vc_column_text][vc_separator type=\u00bbsmall\u00bb position=\u00bbcenter\u00bb color=\u00bb#001d7e\u00bb][\/vc_column][\/vc_row][vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbfull_width\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb][vc_column]<div class='projects_holder_outer v4 portfolio_no_space portfolio_with_hover_text'>\n        <div class='projects_holder portfolio_main_holder clearfix v4  hover_text no_space portfolio_full_image '>\n        \n        <article class='mix default' style=''>\n    \n    \n    \n    \n            <div class=\"item_holder cursor_change_hover\">\n\n                    <div class=\"text_holder\">\n        <div class=\"text_holder_outer\">\n            <div class=\"text_holder_inner\">\n            \n    <h5 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/pujolims.com\/index.php\/portfolio_page\/nova-oficina\/\"  target=\"_self\"> Nova Oficina<\/a><\/h5>\n\n    <span class=\"project_category\"  >\n        <\/span>\n            <\/div>\n        <\/div>\n    <\/div>\n\n                                    <a itemprop=\"url\" class=\"portfolio_link_class\" title=\"Nova Oficina\" href=\"https:\/\/pujolims.com\/index.php\/portfolio_page\/nova-oficina\/\"><\/a>\n                \n                <div style=\"background-color: rgba(0,29,126,0.9)\" class=\"portfolio_shader\"><\/div>\n                <div class=\"image_holder\">\n                    \n<span class='image'><img width=\"1000\" height=\"661\" src=\"https:\/\/pujolims.com\/wp-content\/uploads\/2024\/01\/IMG_2282.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/pujolims.com\/wp-content\/uploads\/2024\/01\/IMG_2282.png 1000w, https:\/\/pujolims.com\/wp-content\/uploads\/2024\/01\/IMG_2282-300x198.png 300w, https:\/\/pujolims.com\/wp-content\/uploads\/2024\/01\/IMG_2282-768x508.png 768w, https:\/\/pujolims.com\/wp-content\/uploads\/2024\/01\/IMG_2282-700x463.png 700w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/span>                <\/div>\n            <\/div>\n\n        \n    \n<\/article>\n<article class='mix large_width' style=''>\n    \n    \n    \n    \n            <div class=\"item_holder cursor_change_hover\">\n\n                    <div class=\"text_holder\">\n        <div class=\"text_holder_outer\">\n            <div class=\"text_holder_inner\">\n            \n    <h5 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/pujolims.com\/index.php\/portfolio_page\/llums-nadal\/\"  target=\"_self\"> Llums Nadal<\/a><\/h5>\n\n    <span class=\"project_category\"  >\n        <\/span>\n            <\/div>\n        <\/div>\n    <\/div>\n\n                                    <a itemprop=\"url\" class=\"portfolio_link_class\" title=\"Llums Nadal\" href=\"https:\/\/pujolims.com\/index.php\/portfolio_page\/llums-nadal\/\"><\/a>\n                \n                <div style=\"background-color: rgba(0,29,126,0.9)\" class=\"portfolio_shader\"><\/div>\n                <div class=\"image_holder\">\n                    \n<span class='image'><img width=\"850\" height=\"567\" src=\"https:\/\/pujolims.com\/wp-content\/uploads\/2023\/12\/portada-llu.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/pujolims.com\/wp-content\/uploads\/2023\/12\/portada-llu.png 850w, https:\/\/pujolims.com\/wp-content\/uploads\/2023\/12\/portada-llu-300x200.png 300w, https:\/\/pujolims.com\/wp-content\/uploads\/2023\/12\/portada-llu-768x512.png 768w, https:\/\/pujolims.com\/wp-content\/uploads\/2023\/12\/portada-llu-700x467.png 700w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/><\/span>                <\/div>\n            <\/div>\n\n        \n    \n<\/article>\n<article class='mix default' style=''>\n    \n    \n    \n    \n            <div class=\"item_holder cursor_change_hover\">\n\n                    <div class=\"text_holder\">\n        <div class=\"text_holder_outer\">\n            <div class=\"text_holder_inner\">\n            \n    <h5 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/pujolims.com\/index.php\/portfolio_page\/suministre-electric-urbanitzacio-vall-de-ruda-vielha\/\"  target=\"_self\"> SUMINISTRE EL\u00c8CTRIC URBANITZACI\u00d3 VALL DE RUDA (VIELHA)<\/a><\/h5>\n\n    <span class=\"project_category\"  >\n        <\/span>\n            <\/div>\n        <\/div>\n    <\/div>\n\n                                    <a itemprop=\"url\" class=\"portfolio_link_class\" title=\"SUMINISTRE EL\u00c8CTRIC URBANITZACI\u00d3 VALL DE RUDA (VIELHA)\" href=\"https:\/\/pujolims.com\/index.php\/portfolio_page\/suministre-electric-urbanitzacio-vall-de-ruda-vielha\/\"><\/a>\n                \n                <div style=\"background-color: rgba(0,29,126,0.9)\" class=\"portfolio_shader\"><\/div>\n                <div class=\"image_holder\">\n                    \n<span class='image'><img width=\"1100\" height=\"825\" src=\"https:\/\/pujolims.com\/wp-content\/uploads\/2021\/08\/suministre-electric-vielha-pujol-ims-4.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/pujolims.com\/wp-content\/uploads\/2021\/08\/suministre-electric-vielha-pujol-ims-4.jpg 1100w, https:\/\/pujolims.com\/wp-content\/uploads\/2021\/08\/suministre-electric-vielha-pujol-ims-4-300x225.jpg 300w, https:\/\/pujolims.com\/wp-content\/uploads\/2021\/08\/suministre-electric-vielha-pujol-ims-4-1024x768.jpg 1024w, https:\/\/pujolims.com\/wp-content\/uploads\/2021\/08\/suministre-electric-vielha-pujol-ims-4-768x576.jpg 768w, https:\/\/pujolims.com\/wp-content\/uploads\/2021\/08\/suministre-electric-vielha-pujol-ims-4-800x600.jpg 800w, https:\/\/pujolims.com\/wp-content\/uploads\/2021\/08\/suministre-electric-vielha-pujol-ims-4-700x525.jpg 700w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/><\/span>                <\/div>\n            <\/div>\n\n        \n    \n<\/article>\n<article class='mix default' style=''>\n    \n    \n    \n    \n            <div class=\"item_holder cursor_change_hover\">\n\n                    <div class=\"text_holder\">\n        <div class=\"text_holder_outer\">\n            <div class=\"text_holder_inner\">\n            \n    <h5 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/pujolims.com\/index.php\/portfolio_page\/caudal-regulacio\/\"  target=\"_self\"> BOMBEIG DE 45 KW AMB CABAL DE REGULACI\u00d3<\/a><\/h5>\n\n    <span class=\"project_category\"  >\n        <\/span>\n            <\/div>\n        <\/div>\n    <\/div>\n\n                                    <a itemprop=\"url\" class=\"portfolio_link_class\" title=\"BOMBEIG DE 45 KW AMB CABAL DE REGULACI\u00d3\" href=\"https:\/\/pujolims.com\/index.php\/portfolio_page\/caudal-regulacio\/\"><\/a>\n                \n                <div style=\"background-color: rgba(0,29,126,0.9)\" class=\"portfolio_shader\"><\/div>\n                <div class=\"image_holder\">\n                    \n<span class='image'><img width=\"1100\" height=\"825\" src=\"https:\/\/pujolims.com\/wp-content\/uploads\/2021\/08\/bombeo-regulado-pujol-ims-6.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/pujolims.com\/wp-content\/uploads\/2021\/08\/bombeo-regulado-pujol-ims-6.jpg 1100w, https:\/\/pujolims.com\/wp-content\/uploads\/2021\/08\/bombeo-regulado-pujol-ims-6-300x225.jpg 300w, https:\/\/pujolims.com\/wp-content\/uploads\/2021\/08\/bombeo-regulado-pujol-ims-6-1024x768.jpg 1024w, https:\/\/pujolims.com\/wp-content\/uploads\/2021\/08\/bombeo-regulado-pujol-ims-6-768x576.jpg 768w, https:\/\/pujolims.com\/wp-content\/uploads\/2021\/08\/bombeo-regulado-pujol-ims-6-800x600.jpg 800w, https:\/\/pujolims.com\/wp-content\/uploads\/2021\/08\/bombeo-regulado-pujol-ims-6-700x525.jpg 700w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/><\/span>                <\/div>\n            <\/div>\n\n        \n    \n<\/article>\n<article class='mix default' style=''>\n    \n    \n    \n    \n            <div class=\"item_holder cursor_change_hover\">\n\n                    <div class=\"text_holder\">\n        <div class=\"text_holder_outer\">\n            <div class=\"text_holder_inner\">\n            \n    <h5 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/pujolims.com\/index.php\/portfolio_page\/establiments\/\"  target=\"_self\"> ESTABLIMENTS I COMER\u00c7OS<\/a><\/h5>\n\n    <span class=\"project_category\"  >\n        <\/span>\n            <\/div>\n        <\/div>\n    <\/div>\n\n                                    <a itemprop=\"url\" class=\"portfolio_link_class\" title=\"ESTABLIMENTS I COMER\u00c7OS\" href=\"https:\/\/pujolims.com\/index.php\/portfolio_page\/establiments\/\"><\/a>\n                \n                <div style=\"background-color: rgba(0,29,126,0.9)\" class=\"portfolio_shader\"><\/div>\n                <div class=\"image_holder\">\n                    \n<span class='image'><img width=\"1100\" height=\"825\" src=\"https:\/\/pujolims.com\/wp-content\/uploads\/2021\/08\/Sargaire-pi-i-maragall-pujol-ims-3.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/pujolims.com\/wp-content\/uploads\/2021\/08\/Sargaire-pi-i-maragall-pujol-ims-3.jpg 1100w, https:\/\/pujolims.com\/wp-content\/uploads\/2021\/08\/Sargaire-pi-i-maragall-pujol-ims-3-300x225.jpg 300w, https:\/\/pujolims.com\/wp-content\/uploads\/2021\/08\/Sargaire-pi-i-maragall-pujol-ims-3-1024x768.jpg 1024w, https:\/\/pujolims.com\/wp-content\/uploads\/2021\/08\/Sargaire-pi-i-maragall-pujol-ims-3-768x576.jpg 768w, https:\/\/pujolims.com\/wp-content\/uploads\/2021\/08\/Sargaire-pi-i-maragall-pujol-ims-3-800x600.jpg 800w, https:\/\/pujolims.com\/wp-content\/uploads\/2021\/08\/Sargaire-pi-i-maragall-pujol-ims-3-700x525.jpg 700w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/><\/span>                <\/div>\n            <\/div>\n\n        \n    \n<\/article>\n<article class='mix default' style=''>\n    \n    \n    \n    \n            <div class=\"item_holder cursor_change_hover\">\n\n                    <div class=\"text_holder\">\n        <div class=\"text_holder_outer\">\n            <div class=\"text_holder_inner\">\n            \n    <h5 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/pujolims.com\/index.php\/portfolio_page\/reforma-xarxa\/\"  target=\"_self\"> REFORMA I SANEJAMENT DE XARXA INFORM\u00c0TICA<\/a><\/h5>\n\n    <span class=\"project_category\"  >\n        <\/span>\n            <\/div>\n        <\/div>\n    <\/div>\n\n                                    <a itemprop=\"url\" class=\"portfolio_link_class\" title=\"REFORMA I SANEJAMENT DE XARXA INFORM\u00c0TICA\" href=\"https:\/\/pujolims.com\/index.php\/portfolio_page\/reforma-xarxa\/\"><\/a>\n                \n                <div style=\"background-color: rgba(0,29,126,0.9)\" class=\"portfolio_shader\"><\/div>\n                <div class=\"image_holder\">\n                    \n<span class='image'><img width=\"1100\" height=\"825\" src=\"https:\/\/pujolims.com\/wp-content\/uploads\/2013\/10\/2.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/pujolims.com\/wp-content\/uploads\/2013\/10\/2.jpg 1100w, https:\/\/pujolims.com\/wp-content\/uploads\/2013\/10\/2-300x225.jpg 300w, https:\/\/pujolims.com\/wp-content\/uploads\/2013\/10\/2-1024x768.jpg 1024w, https:\/\/pujolims.com\/wp-content\/uploads\/2013\/10\/2-768x576.jpg 768w, https:\/\/pujolims.com\/wp-content\/uploads\/2013\/10\/2-800x600.jpg 800w, https:\/\/pujolims.com\/wp-content\/uploads\/2013\/10\/2-700x525.jpg 700w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/><\/span>                <\/div>\n            <\/div>\n\n        \n    \n<\/article>\n<article class='mix default' style=''>\n    \n    \n    \n    \n            <div class=\"item_holder cursor_change_hover\">\n\n                    <div class=\"text_holder\">\n        <div class=\"text_holder_outer\">\n            <div class=\"text_holder_inner\">\n            \n    <h5 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/pujolims.com\/index.php\/portfolio_page\/bombeig-45kw\/\"  target=\"_self\"> BOMBEIG DE 45KW<\/a><\/h5>\n\n    <span class=\"project_category\"  >\n        <\/span>\n            <\/div>\n        <\/div>\n    <\/div>\n\n                                    <a itemprop=\"url\" class=\"portfolio_link_class\" title=\"BOMBEIG DE 45KW\" href=\"https:\/\/pujolims.com\/index.php\/portfolio_page\/bombeig-45kw\/\"><\/a>\n                \n                <div style=\"background-color: rgba(0,29,126,0.9)\" class=\"portfolio_shader\"><\/div>\n                <div class=\"image_holder\">\n                    \n<span class='image'><img width=\"1100\" height=\"825\" src=\"https:\/\/pujolims.com\/wp-content\/uploads\/2013\/10\/quadre-ele\u0300ctric-cassanye-pujol-ims-pdf.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"quadre ele\u0300ctric cassanye pujol ims pdf\" loading=\"lazy\" srcset=\"https:\/\/pujolims.com\/wp-content\/uploads\/2013\/10\/quadre-ele\u0300ctric-cassanye-pujol-ims-pdf.jpg 1100w, https:\/\/pujolims.com\/wp-content\/uploads\/2013\/10\/quadre-ele\u0300ctric-cassanye-pujol-ims-pdf-300x225.jpg 300w, https:\/\/pujolims.com\/wp-content\/uploads\/2013\/10\/quadre-ele\u0300ctric-cassanye-pujol-ims-pdf-1024x768.jpg 1024w, https:\/\/pujolims.com\/wp-content\/uploads\/2013\/10\/quadre-ele\u0300ctric-cassanye-pujol-ims-pdf-768x576.jpg 768w, https:\/\/pujolims.com\/wp-content\/uploads\/2013\/10\/quadre-ele\u0300ctric-cassanye-pujol-ims-pdf-800x600.jpg 800w, https:\/\/pujolims.com\/wp-content\/uploads\/2013\/10\/quadre-ele\u0300ctric-cassanye-pujol-ims-pdf-700x525.jpg 700w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/><\/span>                <\/div>\n            <\/div>\n\n        \n    \n<\/article>\n<article class='mix large_width_height' style=''>\n    \n    \n    \n    \n            <div class=\"item_holder cursor_change_hover\">\n\n                    <div class=\"text_holder\">\n        <div class=\"text_holder_outer\">\n            <div class=\"text_holder_inner\">\n            \n    <h5 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/pujolims.com\/index.php\/portfolio_page\/videovigilancia\/\"  target=\"_self\"> Videovigil\u00e0ncia sistema de comunicaci\u00f3 wifi i rack antivalidaci\u00f3<\/a><\/h5>\n\n    <span class=\"project_category\"  >\n        <\/span>\n            <\/div>\n        <\/div>\n    <\/div>\n\n                                    <a itemprop=\"url\" class=\"portfolio_link_class\" title=\"Videovigil\u00e0ncia sistema de comunicaci\u00f3 wifi i rack antivalidaci\u00f3\" href=\"https:\/\/pujolims.com\/index.php\/portfolio_page\/videovigilancia\/\"><\/a>\n                \n                <div style=\"background-color: rgba(0,29,126,0.9)\" class=\"portfolio_shader\"><\/div>\n                <div class=\"image_holder\">\n                    \n<span class='image'><img width=\"1100\" height=\"825\" src=\"https:\/\/pujolims.com\/wp-content\/uploads\/2013\/10\/gestio-a-distancia-pujol-ims.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"gestio a distancia pujol ims\" loading=\"lazy\" srcset=\"https:\/\/pujolims.com\/wp-content\/uploads\/2013\/10\/gestio-a-distancia-pujol-ims.jpg 1100w, https:\/\/pujolims.com\/wp-content\/uploads\/2013\/10\/gestio-a-distancia-pujol-ims-300x225.jpg 300w, https:\/\/pujolims.com\/wp-content\/uploads\/2013\/10\/gestio-a-distancia-pujol-ims-1024x768.jpg 1024w, https:\/\/pujolims.com\/wp-content\/uploads\/2013\/10\/gestio-a-distancia-pujol-ims-768x576.jpg 768w, https:\/\/pujolims.com\/wp-content\/uploads\/2013\/10\/gestio-a-distancia-pujol-ims-800x600.jpg 800w, https:\/\/pujolims.com\/wp-content\/uploads\/2013\/10\/gestio-a-distancia-pujol-ims-700x525.jpg 700w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/><\/span>                <\/div>\n            <\/div>\n\n        \n    \n<\/article>\n<article class='mix default' style=''>\n    \n    \n    \n    \n            <div class=\"item_holder cursor_change_hover\">\n\n                    <div class=\"text_holder\">\n        <div class=\"text_holder_outer\">\n            <div class=\"text_holder_inner\">\n            \n    <h5 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/pujolims.com\/index.php\/portfolio_page\/xarxa-150-punts-conexio\/\"  target=\"_self\"> XARXA AMB 150 PUNTS DE CONEXI\u00d3<\/a><\/h5>\n\n    <span class=\"project_category\"  >\n        <\/span>\n            <\/div>\n        <\/div>\n    <\/div>\n\n                                    <a itemprop=\"url\" class=\"portfolio_link_class\" title=\"XARXA AMB 150 PUNTS DE CONEXI\u00d3\" href=\"https:\/\/pujolims.com\/index.php\/portfolio_page\/xarxa-150-punts-conexio\/\"><\/a>\n                \n                <div style=\"background-color: rgba(0,29,126,0.9)\" class=\"portfolio_shader\"><\/div>\n                <div class=\"image_holder\">\n                    \n<span class='image'><img width=\"1100\" height=\"825\" src=\"https:\/\/pujolims.com\/wp-content\/uploads\/2013\/10\/xarxa-amb-conexio\u0301-pujol-ims-4.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/pujolims.com\/wp-content\/uploads\/2013\/10\/xarxa-amb-conexio\u0301-pujol-ims-4.jpg 1100w, https:\/\/pujolims.com\/wp-content\/uploads\/2013\/10\/xarxa-amb-conexio\u0301-pujol-ims-4-300x225.jpg 300w, https:\/\/pujolims.com\/wp-content\/uploads\/2013\/10\/xarxa-amb-conexio\u0301-pujol-ims-4-1024x768.jpg 1024w, https:\/\/pujolims.com\/wp-content\/uploads\/2013\/10\/xarxa-amb-conexio\u0301-pujol-ims-4-768x576.jpg 768w, https:\/\/pujolims.com\/wp-content\/uploads\/2013\/10\/xarxa-amb-conexio\u0301-pujol-ims-4-800x600.jpg 800w, https:\/\/pujolims.com\/wp-content\/uploads\/2013\/10\/xarxa-amb-conexio\u0301-pujol-ims-4-700x525.jpg 700w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/><\/span>                <\/div>\n            <\/div>\n\n        \n    \n<\/article>\n<article class='mix large_width' style=''>\n    \n    \n    \n    \n            <div class=\"item_holder cursor_change_hover\">\n\n                    <div class=\"text_holder\">\n        <div class=\"text_holder_outer\">\n            <div class=\"text_holder_inner\">\n            \n    <h5 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/pujolims.com\/index.php\/portfolio_page\/porters-automatics\/\"  target=\"_self\"> Porters autom\u00e0tics<\/a><\/h5>\n\n    <span class=\"project_category\"  >\n        <\/span>\n            <\/div>\n        <\/div>\n    <\/div>\n\n                                    <a itemprop=\"url\" class=\"portfolio_link_class\" title=\"Porters autom\u00e0tics\" href=\"https:\/\/pujolims.com\/index.php\/portfolio_page\/porters-automatics\/\"><\/a>\n                \n                <div style=\"background-color: rgba(0,29,126,0.9)\" class=\"portfolio_shader\"><\/div>\n                <div class=\"image_holder\">\n                    \n<span class='image'><img width=\"1100\" height=\"825\" src=\"https:\/\/pujolims.com\/wp-content\/uploads\/2013\/10\/porters-automa\u0300tics-pujol-ims.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"porters automa\u0300tics pujol ims\" loading=\"lazy\" srcset=\"https:\/\/pujolims.com\/wp-content\/uploads\/2013\/10\/porters-automa\u0300tics-pujol-ims.jpg 1100w, https:\/\/pujolims.com\/wp-content\/uploads\/2013\/10\/porters-automa\u0300tics-pujol-ims-300x225.jpg 300w, https:\/\/pujolims.com\/wp-content\/uploads\/2013\/10\/porters-automa\u0300tics-pujol-ims-1024x768.jpg 1024w, https:\/\/pujolims.com\/wp-content\/uploads\/2013\/10\/porters-automa\u0300tics-pujol-ims-768x576.jpg 768w, https:\/\/pujolims.com\/wp-content\/uploads\/2013\/10\/porters-automa\u0300tics-pujol-ims-800x600.jpg 800w, https:\/\/pujolims.com\/wp-content\/uploads\/2013\/10\/porters-automa\u0300tics-pujol-ims-700x525.jpg 700w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/><\/span>                <\/div>\n            <\/div>\n\n        \n    \n<\/article>\n<article class='mix default' style=''>\n    \n    \n    \n    \n            <div class=\"item_holder cursor_change_hover\">\n\n                    <div class=\"text_holder\">\n        <div class=\"text_holder_outer\">\n            <div class=\"text_holder_inner\">\n            \n    <h5 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/pujolims.com\/index.php\/portfolio_page\/quadres-electrics\/\"  target=\"_self\"> Quadres el\u00e8ctrics<\/a><\/h5>\n\n    <span class=\"project_category\"  >\n        <\/span>\n            <\/div>\n        <\/div>\n    <\/div>\n\n                                    <a itemprop=\"url\" class=\"portfolio_link_class\" title=\"Quadres el\u00e8ctrics\" href=\"https:\/\/pujolims.com\/index.php\/portfolio_page\/quadres-electrics\/\"><\/a>\n                \n                <div style=\"background-color: rgba(0,29,126,0.9)\" class=\"portfolio_shader\"><\/div>\n                <div class=\"image_holder\">\n                    \n<span class='image'><img width=\"1100\" height=\"825\" src=\"https:\/\/pujolims.com\/wp-content\/uploads\/2013\/10\/quadre-electric-pujol-ims_26.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/pujolims.com\/wp-content\/uploads\/2013\/10\/quadre-electric-pujol-ims_26.jpg 1100w, https:\/\/pujolims.com\/wp-content\/uploads\/2013\/10\/quadre-electric-pujol-ims_26-300x225.jpg 300w, https:\/\/pujolims.com\/wp-content\/uploads\/2013\/10\/quadre-electric-pujol-ims_26-1024x768.jpg 1024w, https:\/\/pujolims.com\/wp-content\/uploads\/2013\/10\/quadre-electric-pujol-ims_26-768x576.jpg 768w, https:\/\/pujolims.com\/wp-content\/uploads\/2013\/10\/quadre-electric-pujol-ims_26-800x600.jpg 800w, https:\/\/pujolims.com\/wp-content\/uploads\/2013\/10\/quadre-electric-pujol-ims_26-700x525.jpg 700w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/><\/span>                <\/div>\n            <\/div>\n\n        \n    \n<\/article>\n<article class='mix default' style=''>\n    \n    \n    \n    \n            <div class=\"item_holder cursor_change_hover\">\n\n                    <div class=\"text_holder\">\n        <div class=\"text_holder_outer\">\n            <div class=\"text_holder_inner\">\n            \n    <h5 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/pujolims.com\/index.php\/portfolio_page\/bombeig-solar\/\"  target=\"_self\"> Bombeig solar<\/a><\/h5>\n\n    <span class=\"project_category\"  >\n        <\/span>\n            <\/div>\n        <\/div>\n    <\/div>\n\n                                    <a itemprop=\"url\" class=\"portfolio_link_class\" title=\"Bombeig solar\" href=\"https:\/\/pujolims.com\/index.php\/portfolio_page\/bombeig-solar\/\"><\/a>\n                \n                <div style=\"background-color: rgba(0,29,126,0.9)\" class=\"portfolio_shader\"><\/div>\n                <div class=\"image_holder\">\n                    \n<span class='image'><img width=\"1100\" height=\"825\" src=\"https:\/\/pujolims.com\/wp-content\/uploads\/2013\/10\/placa-solar-pujol-ims.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"placa solar pujol ims\" loading=\"lazy\" srcset=\"https:\/\/pujolims.com\/wp-content\/uploads\/2013\/10\/placa-solar-pujol-ims.jpg 1100w, https:\/\/pujolims.com\/wp-content\/uploads\/2013\/10\/placa-solar-pujol-ims-300x225.jpg 300w, https:\/\/pujolims.com\/wp-content\/uploads\/2013\/10\/placa-solar-pujol-ims-1024x768.jpg 1024w, https:\/\/pujolims.com\/wp-content\/uploads\/2013\/10\/placa-solar-pujol-ims-768x576.jpg 768w, https:\/\/pujolims.com\/wp-content\/uploads\/2013\/10\/placa-solar-pujol-ims-800x600.jpg 800w, https:\/\/pujolims.com\/wp-content\/uploads\/2013\/10\/placa-solar-pujol-ims-700x525.jpg 700w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/><\/span>                <\/div>\n            <\/div>\n\n        \n    \n<\/article>\n        <div class='filler'><\/div>\n            <div class='filler'><\/div>\n            <div class='filler'><\/div>\n            <div class='filler'><\/div>\n        <\/div>\n\n    \n    <\/div>[\/vc_column][\/vc_row][vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbfull_width\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb][vc_column]<div class=\"call_to_action normal\" style=\"background-color: #353535;\"><div class=\"container_inner\"><div class=\"two_columns_75_25 clearfix\"><div class=\"text_wrapper column1\"><div class=\"call_to_action_text  font_size_inherit font_weight_inherit\" style=\"font-size:16px;font-weight: 400;\">\n<h5><span style=\"color: #ffffff; font-size: 16px; letter-spacing: 1px;\">Si necessites un dels nostres serveis, no dubtis en contactar amb nosaltres<\/span><\/h5>\n<\/div><\/div><div class=\"button_wrapper column2\"><a itemprop=\"url\" href=\"#\" class=\"qbutton white \" target=\"_self\" style=\"color: #ffffff;border-color: #001d7e;background-color: #001d7e;\" data-hover-background-color=#353535 data-hover-border-color=#001d7e data-hover-color=#ffffff>contaca'ns<\/a><\/div><\/div><\/div><\/div>[\/vc_column][\/vc_row][vc_row row_type=\u00bbparallax\u00bb parallax_content_width=\u00bbin_grid\u00bb text_align=\u00bbcenter\u00bb full_screen_section_height=\u00bbno\u00bb background_image=\u00bb15951&#8243; section_height=\u00bb300&#8243; anchor=\u00bbcontact\u00bb][vc_column width=\u00bb1\/3&#8243;][vc_separator type=\u00bbtransparent\u00bb thickness=\u00bb1&#8243; up=\u00bb83&#8243; down=\u00bb0&#8243;]<div class='q_icon_with_title large custom_icon_image center '><div class=\"icon_holder \" style=\" \"><img itemprop=\"image\" style=\"\" src=\"https:\/\/pujolims.com\/wp-content\/uploads\/2021\/05\/Contacto-pujol-ims-almacelles-01.png\" alt=\"\"><\/div><div class=\"icon_text_holder\" style=\"\"><div class=\"icon_text_inner\" style=\"\"><h5 class=\"icon_title\" style=\"\">696 83 00 18<\/h5><p style=''><\/p><\/div><\/div><\/div>[\/vc_column][vc_column width=\u00bb1\/3&#8243;][vc_separator type=\u00bbtransparent\u00bb thickness=\u00bb1&#8243; up=\u00bb83&#8243; down=\u00bb0&#8243;]<div class='q_icon_with_title large custom_icon_image center '><div class=\"icon_holder \" style=\" \"><img itemprop=\"image\" style=\"\" src=\"https:\/\/pujolims.com\/wp-content\/uploads\/2021\/05\/Contacto-pujol-ims-almacelles-02.png\" alt=\"\"><\/div><div class=\"icon_text_holder\" style=\"\"><div class=\"icon_text_inner\" style=\"\"><h5 class=\"icon_title\" style=\"\">pujol.ims@gmail.com<\/h5><p style=''><\/p><\/div><\/div><\/div>[\/vc_column][vc_column width=\u00bb1\/3&#8243;][vc_separator type=\u00bbtransparent\u00bb thickness=\u00bb1&#8243; up=\u00bb83&#8243; down=\u00bb0&#8243;]<div class='q_icon_with_title large custom_icon_image center '><div class=\"icon_holder \" style=\" \"><img itemprop=\"image\" style=\"\" src=\"https:\/\/pujolims.com\/wp-content\/uploads\/2021\/05\/Contacto-pujol-ims-almacelles-03.png\" alt=\"\"><\/div><div class=\"icon_text_holder\" style=\"\"><div class=\"icon_text_inner\" style=\"\"><h5 class=\"icon_title\" style=\"\">c\/ De la Merc\u00e8 37. 25100 Almacelles (Lleida)<\/h5><p style=''><\/p><\/div><\/div><\/div>[\/vc_column][\/vc_row][vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbgrid\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb padding_top=\u00bb81&#8243; padding_bottom=\u00bb115&#8243;][vc_column width=\u00bb1\/2&#8243;][vc_column_text]<\/p>\n<h5 style=\"text-align: left;\">Contacta amb Pujol IMS<\/h5>\n<p>[\/vc_column_text][vc_separator type=\u00bbtransparent\u00bb thickness=\u00bb1&#8243; up=\u00bb39&#8243; down=\u00bb0&#8243;][vc_column_text]Per qualsevol treball, estudi o consulta, no dubteu en posar-vos en contacte amb nosaltres, atendrem les vostres necessitats de forma personalitzada, buscant solucions per cada cas.<\/p>\n<p>Per fer-ho podeu omplir aquest questionari o trucar-nos al 696 83 00 18.<\/p>\n<p><strong>Sempre al vostre servei.<\/strong>[\/vc_column_text][\/vc_column][vc_column width=\u00bb1\/2&#8243;]<div role=\"form\" class=\"wpcf7\" id=\"wpcf7-f6-o1\" lang=\"es-ES\" dir=\"ltr\">\n<div class=\"screen-reader-response\" role=\"alert\" aria-live=\"polite\"><\/div>\n<form action=\"\/index.php\/wp-json\/wp\/v2\/pages\/15508#wpcf7-f6-o1\" method=\"post\" class=\"wpcf7-form init default\" novalidate=\"novalidate\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"6\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.2.2\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f6-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<p><label> Nom (obligatori)<br \/>\n    <span class=\"wpcf7-form-control-wrap your-name\"><input type=\"text\" name=\"your-name\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><label> E-mail (obligatori)<br \/>\n    <span class=\"wpcf7-form-control-wrap your-email\"><input type=\"email\" name=\"your-email\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><label> Assumpte<br \/>\n    <span class=\"wpcf7-form-control-wrap your-subject\"><input type=\"text\" name=\"your-subject\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><label> Missatge<br \/>\n    <span class=\"wpcf7-form-control-wrap your-message\"><textarea name=\"your-message\" cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\"><\/textarea><\/span> <\/label><\/p>\n<p><span class=\"wpcf7-form-control-wrap checkbox-514\"><span class=\"wpcf7-form-control wpcf7-checkbox wpcf7-validates-as-required\"><span class=\"wpcf7-list-item first last\"><input type=\"checkbox\" name=\"checkbox-514[]\" value=\"Al marcar aquesta cassella accepto la pol\u00edtica de privacitat d&#039;aquesta web.\" \/><span class=\"wpcf7-list-item-label\">Al marcar aquesta cassella accepto la pol\u00edtica de privacitat d&#039;aquesta web.<\/span><\/span><\/span><\/span><\/p>\n<p><span class=\"wpcf7-form-control-wrap checkbox-222\"><span class=\"wpcf7-form-control wpcf7-checkbox wpcf7-validates-as-required\"><span class=\"wpcf7-list-item first last\"><input type=\"checkbox\" name=\"checkbox-222[]\" value=\"Pujol ims com a responsable del tractament i legitimat pel teu consentiment tractar\u00e0 les teves dades amb la finalitat de gestionar la sol\u00b7licitud que realitzes en aquesta web. Les teves dades estar\u00e0n alotjades a la nostra plataforma de hosting Tens dret a accedir, rectificar i oposarte i suprimir les teves dades, aix\u00ed com altres dretes, a pujol.ims@gmail.com o davant l&#039;autoritat de control. Tens informaci\u00f3 adicional als avisos legals.\" \/><span class=\"wpcf7-list-item-label\">Pujol ims com a responsable del tractament i legitimat pel teu consentiment tractar\u00e0 les teves dades amb la finalitat de gestionar la sol\u00b7licitud que realitzes en aquesta web. Les teves dades estar\u00e0n alotjades a la nostra plataforma de hosting Tens dret a accedir, rectificar i oposarte i suprimir les teves dades, aix\u00ed com altres dretes, a pujol.ims@gmail.com o davant l&#039;autoritat de control. Tens informaci\u00f3 adicional als avisos legals.<\/span><\/span><\/span><\/span><\/p>\n<p><input type=\"submit\" value=\"Enviar\" class=\"wpcf7-form-control wpcf7-submit\" \/><\/p>\n<div class=\"wpcf7-response-output\" role=\"alert\" aria-hidden=\"true\"><\/div><\/form><\/div>[\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbgrid\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbcenter\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb padding_top=\u00bb65&#8243; padding_bottom=\u00bb118&#8243; anchor=\u00bbabout\u00bb][vc_column][vc_column_text] Sobre nosaltres [\/vc_column_text][vc_separator type=\u00bbsmall\u00bb position=\u00bbcenter\u00bb color=\u00bb#001d7e\u00bb][vc_column_text] Pujol ims \u00e9s una empresa formada&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"full_width.php","meta":[],"_links":{"self":[{"href":"https:\/\/pujolims.com\/index.php\/wp-json\/wp\/v2\/pages\/15508"}],"collection":[{"href":"https:\/\/pujolims.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/pujolims.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/pujolims.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pujolims.com\/index.php\/wp-json\/wp\/v2\/comments?post=15508"}],"version-history":[{"count":44,"href":"https:\/\/pujolims.com\/index.php\/wp-json\/wp\/v2\/pages\/15508\/revisions"}],"predecessor-version":[{"id":16212,"href":"https:\/\/pujolims.com\/index.php\/wp-json\/wp\/v2\/pages\/15508\/revisions\/16212"}],"wp:attachment":[{"href":"https:\/\/pujolims.com\/index.php\/wp-json\/wp\/v2\/media?parent=15508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}